{"id":3434,"date":"2022-09-12T15:06:03","date_gmt":"2022-09-12T15:06:03","guid":{"rendered":"https:\/\/turisme.olocau.es\/el-turista-i-viatger-responsable\/"},"modified":"2026-04-22T08:26:25","modified_gmt":"2026-04-22T08:26:25","slug":"el-turista-i-viatger-responsable","status":"publish","type":"page","link":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/","title":{"rendered":"El Turista i Viatger Responsable"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3434\" class=\"elementor elementor-3434 elementor-2108\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25edd5fd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"25edd5fd\" data-element_type=\"section\" data-e-type=\"section\" id=\"arriba\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-340ecdf7\" data-id=\"340ecdf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33525be3 elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"33525be3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\" dir=\"ltr\" data-animation=\"fadeInLeft\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-f782748 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fa9385 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fa9385\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71b407d0\" data-id=\"71b407d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c3c4bae elementor-widget elementor-widget-image\" data-id=\"2c3c4bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"202\" height=\"253\" src=\"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png\" class=\"attachment-large size-large wp-image-2634\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c5b443d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c5b443d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61481f0e\" data-id=\"61481f0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6363653e elementor-widget elementor-widget-heading\" data-id=\"6363653e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Turista i Viatger Responsable<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4de425e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4de425e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81e33f0\" data-id=\"81e33f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5a8f9e elementor-widget elementor-widget-text-editor\" data-id=\"b5a8f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Els viatges i el turisme haurien de concebre&#8217;s i practicar-se com un mitj\u00e0 de desenvolupament personal i col\u00b7lectiu. Si es duen a terme amb una ment oberta, s\u00f3n un factor insubstitu\u00efble d&#8217;autoeducaci\u00f3, toler\u00e0ncia m\u00fatua i aprenentatge de les leg\u00edtimes difer\u00e8ncies i cultures i de la seua diversitat. <\/p>\n<p>Tots tenim una funci\u00f3 que complir en la generaci\u00f3 de viatges i turisme responsables. Els governs, les empreses i les comunitats han de procurar-ho sens dubte per tots els mitjans, per\u00f2 vost\u00e9 tamb\u00e9, en la seua qualitat de visitant, pot secundar sensiblement aquest objectiu de moltes maneres: <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-410b5ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"410b5ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85ead58\" data-id=\"85ead58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3388944 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3388944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star-and-crescent\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e1f0781\" data-id=\"e1f0781\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0db1b6d elementor-widget elementor-widget-text-editor\" data-id=\"0db1b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>\u00d2briga&#8217;s a les cultures i tradicions diferents de les seues:<\/b> la seua experi\u00e8ncia es veur\u00e0 transformada, vost\u00e9 es guanyar\u00e0 el respecte de la poblaci\u00f3 local, i aquesta l&#8217;acollir\u00e0 m\u00e9s f\u00e0cilment. Siga tolerant i respecte la diversitat; observe les tradicions i les pr\u00e0ctiques socials i culturals del lloc. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55d0173 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55d0173\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9de6275\" data-id=\"9de6275\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9822e9d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9822e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-person-booth\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64cc6b4\" data-id=\"64cc6b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e4ef8c elementor-widget elementor-widget-text-editor\" data-id=\"4e4ef8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Respecte els drets humans. <\/b>Qualsevol forma d&#8217;explotaci\u00f3 vulnera els objectius fonamentals del turisme. L&#8217;explotaci\u00f3 sexual infantil \u00e9s un delicte punible, tant en el lloc on es duga a terme com al pa\u00eds de resid\u00e8ncia de qui el cometa. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f733736 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f733736\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17e3d65\" data-id=\"17e3d65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e804f7 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0e804f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tree\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ec828b\" data-id=\"6ec828b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e0a52f elementor-widget elementor-widget-text-editor\" data-id=\"3e0a52f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ajude a conservar l&#8217;entorn natural. <\/b>Protegisca la flora i fauna silvestre i el seu h\u00e0bitat, i no compre productes elaborats a partir de plantes o animals en perill d&#8217;extinci\u00f3.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5312e57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5312e57\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dedff60\" data-id=\"dedff60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760f9bf elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"760f9bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-boxes\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-064b2b4\" data-id=\"064b2b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e15aae9 elementor-widget elementor-widget-text-editor\" data-id=\"e15aae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Respecte els recursos culturals. <\/b>Les activitats tur\u00edstiques han de practicar-se amb respecte pel patrimoni art\u00edstic, arqueol\u00f2gic i cultural.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab4432a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab4432a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0842528\" data-id=\"0842528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbdedd4 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bbdedd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ticket-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f7ac34\" data-id=\"8f7ac34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18ac758 elementor-widget elementor-widget-text-editor\" data-id=\"18ac758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\"><strong>Contribueixi al desenvolupament econ\u00f2mic i social<\/strong>. Compri artesania i productes locals per a donar suport a l&#8217;economia del lloc, i atingui&#8217;s als principis del comer\u00e7 just. Quan regategi, tingui present el concepte de salari just.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb59e5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb59e5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-010852b\" data-id=\"010852b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7abd70c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7abd70c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-ambulance\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ad4ee80\" data-id=\"ad4ee80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-063ec70 elementor-widget elementor-widget-text-editor\" data-id=\"063ec70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abans d&#8217;eixir de viatge, i<b>nforme&#8217;s sobre la situaci\u00f3 sanit\u00e0ria actual del seu dest\u00ed<\/b> i sobre l&#8217;acc\u00e9s en ell a serveis consulars i d&#8217;emerg\u00e8ncia, i assegure&#8217;s que la seua salut i la seua seguretat personal no correran perill. Cerciore&#8217;s de tindre cobertes all\u00ed les seues necessitats espec\u00edfiques (alimentaci\u00f3, accessibilitat o atenci\u00f3 m\u00e8dica) abans de decidir-se a viatjar a un dest\u00ed determinat. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59e6878 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59e6878\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b8aaf91\" data-id=\"b8aaf91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a64b01 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5a64b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-torah\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-91b860a\" data-id=\"91b860a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7639d elementor-widget elementor-widget-text-editor\" data-id=\"bc7639d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Reunisca tota la informaci\u00f3 possible sobre el seu dest\u00ed, i <b>dedique temps a entendre els seus costums, normes i tradicions.<\/b> Evite els comportaments que puguen ofendre a la poblaci\u00f3 local. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-348f010 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"348f010\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f80cd3\" data-id=\"2f80cd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b843d4a elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b843d4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-capsules\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a495af\" data-id=\"4a495af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2969d13 elementor-widget elementor-widget-text-editor\" data-id=\"2969d13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Informe&#8217;s de la legislaci\u00f3 vigent<\/b> per a no cometre cap acte que es considere delictiu al pa\u00eds visitat. No trafique amb drogues, armes, antiguitats, esp\u00e8cies protegides, productes o subst\u00e0ncies perilloses o prohibides pels reglaments nacionals. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bc6084 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bc6084\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0547de\" data-id=\"b0547de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b02988 elementor-widget elementor-widget-text-editor\" data-id=\"2b02988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aquests consells es basen en el <i>Codi \u00c8tic Mundial per al Turisme<\/i> de l&#8217;Organitzaci\u00f3 Mundial del Turisme.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fc9b38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fc9b38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65d71bc\" data-id=\"65d71bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d6450 elementor-widget elementor-widget-text-editor\" data-id=\"14d6450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"blog-post \"><div class=\"container\" role=\"main\" aria-label=\"Contenido principal\"><article id=\"post-3810\" class=\"section section-text\"><div class=\"row\"><div class=\"col-md-8 page-content-wrap col-md-offset-2\"><div class=\"blog-post \"><div class=\"container\" role=\"main\" aria-label=\"Contenido principal\"><article id=\"post-3810\" class=\"section section-text\"><div class=\"row\"><h1>Drets i obligacions del turista<\/h1><h4>La Comunitat Valenciana compta amb la Llei de Turisme, que estableix els drets de les persones usu\u00e0ries de serveis i productes tur\u00edstics.<\/h4><p>La LLEI 15\/2018, 7 de juny, de turisme, oci i hospitalitat de la Comunitat Valenciana contempla l&#8217;impuls de l&#8217;hospitalitat com a element b\u00e0sic en la relaci\u00f3 entre residents i turistes.<\/p><p>Aquesta Llei defineix l&#8217;Hospitalitat com la \u201catenci\u00f3 i tracte proporcionat a les persones usu\u00e0ries de serveis tur\u00edstics des del respecte al seu idioma, h\u00e0bits, tradicions, creences i llibertat de consci\u00e8ncia, amb la finalitat de proporcionar la major satisfacci\u00f3 possible de les seues expectatives d&#8217;acord amb els valors que ens identifiquen com a societat oberta, tolerant i mediterr\u00e0nia.\u201d<\/p><p>Els Articles 16 i 17 de la citada Llei desenvolupen els drets i deures dels usuaris dels serveis tur\u00edstics per a preservar aquest pilar central de la relaci\u00f3 entre els turistes que ens visiten i el nostre dest\u00ed:<\/p><p>\u00a0<\/p><p><br \/><strong>Article 16. Drets<\/strong><\/p><p>Les persones usu\u00e0ries de serveis tur\u00edstics, sense perjudici del que es disposa en la legislaci\u00f3 general de defensa i protecci\u00f3 dels consumidors, tindran dret a:<\/p><p>Rebre de les empreses tur\u00edstiques informaci\u00f3 objectiva, vera\u00e7 i comprensible, completa i pr\u00e8via a la seua contractaci\u00f3 sobre els serveis que se&#8217;ls oferisquen, aix\u00ed com sobre el preu final, inclosos els impostos. I a ser protegit enfront de la informaci\u00f3 o publicitat enganyosa conformement a la normativa vigent.<br \/>Obtindre els documents que acrediten els termes de la seua contractaci\u00f3.<br \/>Rebre els serveis tur\u00edstics en les condicions oferides o pactades i, en tot cas, que la naturalesa i qualitat de la seua prestaci\u00f3 guarde proporci\u00f3 directa amb la categoria de l&#8217;empresa o establiment tur\u00edstic.<br \/>Gaudir d&#8217;uns espais, infraestructures i serveis tur\u00edstics accessibles.<br \/>Accedir lliurement als establiments i serveis tur\u00edstics en els termes establits en les lleis.<br \/>Que els establiments tur\u00edstics complisquen la normativa sobre seguretat de les seues instal\u00b7lacions i protecci\u00f3 contra incendis aix\u00ed com l&#8217;espec\u00edfica en mat\u00e8ria tur\u00edstica.<br \/>Ser informats, de manera clara, sobre les instal\u00b7lacions o serveis que puguen suposar algun risc i de les mesures de seguretat adoptades sobre aquest tema.<br \/>Rebre una factura o justificant de pagament del servei tur\u00edstic prestat amb les dades que la legislaci\u00f3 vigent exigisca.<br \/>Formular queixes i reclamacions i obtindre informaci\u00f3 accessible i vera\u00e7 sobre el procediment de presentaci\u00f3 de les mateixes i el seu tractament, podent acudir a un sistema de soluci\u00f3 extrajudicial de conflictes a trav\u00e9s de la mediaci\u00f3 i l&#8217;arbitratge. Aix\u00ed mateix, tenen dret al fet que l&#8217;administraci\u00f3 p\u00fablica competent procure la m\u00e0xima efic\u00e0cia en l&#8217;atenci\u00f3 i tramitaci\u00f3 de les seues queixes o reclamacions formulades.<br \/>Acudir a f\u00f3rmules d&#8217;arbitratge per a la resoluci\u00f3 extrajudicial dels seus conflictes amb conseq\u00fc\u00e8ncies econ\u00f2miques.<br \/>Exigir que, en un lloc de f\u00e0cil visibilitat, s&#8217;exhibisquen p\u00fablicament els distintius acreditatius de la classificaci\u00f3 de l&#8217;establiment, l&#8217;aforament, els preus dels serveis oferits i qualsevol altra variable d&#8217;activitat, aix\u00ed com els s\u00edmbols de qualitat corresponents.<\/p><p>\u00a0<\/p><p><br \/><strong>Article 17. Obligacions<\/strong><\/p><p>Les persones usu\u00e0ries de serveis tur\u00edstics, sense perjudici del que disposen les normatives sectorials que siguen aplicable, tindran les seg\u00fcents obligacions:<\/p><p>Respectar les tradicions i pr\u00e0ctiques socials i culturals de les destinacions tur\u00edstiques, aix\u00ed com la seua riquesa i valor.<br \/>Respectar l&#8217;entorn mediambiental, el patrimoni hist\u00f2ric i cultural i els recursos tur\u00edstics.<br \/>Abonar els serveis contractats, ja siga en el moment de la presentaci\u00f3 de la factura o en el temps, lloc i forma convinguts, sense que el fet de presentar una reclamaci\u00f3 o queixa implique, en cap cas, l&#8217;exempci\u00f3 de pagament.<br \/>En el cas del servei tur\u00edstic d&#8217;allotjament, respectar la data i hora pactades d&#8217;eixida de l&#8217;establiment, deixant lliure la unitat d&#8217;allotjament ocupada.<br \/>Observar les regles de respecte, educaci\u00f3, conviv\u00e8ncia social, indument\u00e0ria i higiene per a l&#8217;adequada utilitzaci\u00f3 dels establiments i serveis tur\u00edstics.<br \/>Respectar les instal\u00b7lacions i equipaments dels establiments i empreses tur\u00edstiques.<br \/>Respectar les normes de r\u00e8gim interior dels establiments tur\u00edstics, els horaris i les regles de conducta dels llocs de visita i de realitzaci\u00f3 d&#8217;activitats tur\u00edstiques.<\/p><p><strong>M\u00e9s\u2026<\/strong><\/p><p>Els viatgers i el turista haurien de concebre&#8217;s com un mitj\u00e0 de desenvolupament personal i col\u00b7lectiu. Si es duen a terme amb una ment oberta, s\u00f3n un factor insubstitu\u00efble d&#8217;acte educaci\u00f3, toler\u00e0ncia m\u00fatua i aprenentatge de les leg\u00edtimes diferencies ens pobles i cultures i de la seua diversitat.<\/p><p>Tots tenim una funci\u00f3 que complir en la generaci\u00f3 de viatges i turisme responsables. Els governs, les empreses i les comunitats han de procurar el sens dubte per tots els mitjans, per\u00f2 vost\u00e9 tamb\u00e9, en la seua qualitat de visitant, pot secundar sensiblement aquest objectiu de moltes maneres:<\/p><ul><li>\u00d2briga&#8217;s a les cultures i tradicions diferents de les seues: la seua experi\u00e8ncia es veur\u00e0 transformada, vost\u00e9 es guanyar\u00e0 el respecte de les poblaci\u00f3 local, i aquesta l&#8217;acollir\u00e0 m\u00e9s f\u00e0cilment. Siga tolerant i respecte la diversitat; observe les tradicions i les pr\u00e0ctiques socials i culturals del lloc.<\/li><li>Respecte els drets humans. Qualsevol forma d&#8217;explotaci\u00f3 vulnera els objectius fonamentals del turisme. L&#8217;explotaci\u00f3 sexual infantil \u00e9s un delicte punible, tant en el lloc on \u00e9s duga a terme com al pa\u00eds de resid\u00e8ncia de qui el cometa.<\/li><li>Ajude a conservar l&#8217;entorn natural. Protegisca la flora i la fauna silvestre i el seu h\u00e0bitat, i no compre productes elaborats a partir de plantes o animals en perill d&#8217;extinci\u00f3.<\/li><li>Respecte els recursos culturals. Les activitats tur\u00edstiques han de practicar-se amb respecte pel patrimoni art\u00edstics, arqueol\u00f2gic i cultural.<\/li><li>El seu viatge pot contribuir al desenvolupament econ\u00f2mic i social. Compre artesania i productes locals per a donar suport a l&#8217;economia del lloc, i atinga&#8217;s als principis del comer\u00e7 just. Quan regatege, tinga premse el concepte del salari just.<\/li><li>Abans d&#8217;eixir de viatge, informe&#8217;s sobre la situaci\u00f3 sanit\u00e0ria actual del seu dest\u00ed i sobre l&#8217;acc\u00e9s en ell a serveis consulars i d&#8217;emerg\u00e8ncia, i assegure&#8217;s que la seua salut i la seua seguretat personal no correran perill. Cerciore&#8217;s de tindre cobertes all\u00ed les seues necessitats espec\u00edfiques (alimentaci\u00f3, accessibilitat o atenci\u00f3 m\u00e8dica) abans de decidir-se a viatjar a un dest\u00ed determinat.<\/li><li>Reunisca tota la informaci\u00f3 possible sobre el seu dest\u00ed, i dedique temps a entendre els seus costums, normes i tradicions. Evite els comportaments que puguen ofendre a la poblaci\u00f3 local.<br \/>Informe&#8217;s de la legislaci\u00f3 vigent per a no cometre cap acte que es considere delictiu al pa\u00eds visitat. No trafique amb drogues, armes, antiguitats, espeies protegides, ni productes o subst\u00e0ncies perillosos o prohibits pels reglaments nacionals.<\/li><\/ul><\/div><\/article><\/div><\/div><\/div><\/div><\/article><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El Turista i Viatger Responsable Els viatges i el turisme haurien de concebre&#8217;s i practicar-se com un mitj\u00e0 de desenvolupament personal i col\u00b7lectiu. Si es duen a terme amb una ment oberta, s\u00f3n un factor insubstitu\u00efble d&#8217;autoeducaci\u00f3, toler\u00e0ncia m\u00fatua i aprenentatge de les leg\u00edtimes difer\u00e8ncies i cultures i de la seua diversitat. Tots tenim una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-3434","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Turista i Viatger Responsable - Turismo Olocau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Turista i Viatger Responsable - Turismo Olocau\" \/>\n<meta property=\"og:description\" content=\"El Turista i Viatger Responsable Els viatges i el turisme haurien de concebre&#8217;s i practicar-se com un mitj\u00e0 de desenvolupament personal i col\u00b7lectiu. Si es duen a terme amb una ment oberta, s\u00f3n un factor insubstitu\u00efble d&#8217;autoeducaci\u00f3, toler\u00e0ncia m\u00fatua i aprenentatge de les leg\u00edtimes difer\u00e8ncies i cultures i de la seua diversitat. Tots tenim una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo Olocau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Turisme-Olocau-110345021644060\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T08:26:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png\" \/>\n\t<meta property=\"og:image:width\" content=\"202\" \/>\n\t<meta property=\"og:image:height\" content=\"253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@turismeolocau\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/\",\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/\",\"name\":\"El Turista i Viatger Responsable - Turismo Olocau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/muestras.png\",\"datePublished\":\"2022-09-12T15:06:03+00:00\",\"dateModified\":\"2026-04-22T08:26:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/#breadcrumb\"},\"inLanguage\":\"val\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"val\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/muestras.png\",\"contentUrl\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/muestras.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/el-turista-i-viatger-responsable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Turista i Viatger Responsable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/\",\"name\":\"Turismo Olocau\",\"description\":\"Visita Olocau\",\"publisher\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"val\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#organization\",\"name\":\"Turismo Olocau\",\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"val\",\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Olocau-turismo_color.png\",\"contentUrl\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Logo-Olocau-turismo_color.png\",\"width\":300,\"height\":123,\"caption\":\"Turismo Olocau\"},\"image\":{\"@id\":\"https:\\\/\\\/turisme.olocau.es\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Turisme-Olocau-110345021644060\",\"https:\\\/\\\/x.com\\\/turismeolocau\",\"https:\\\/\\\/www.instagram.com\\\/turismeolocau\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Turista i Viatger Responsable - Turismo Olocau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/","og_locale":"en_US","og_type":"article","og_title":"El Turista i Viatger Responsable - Turismo Olocau","og_description":"El Turista i Viatger Responsable Els viatges i el turisme haurien de concebre&#8217;s i practicar-se com un mitj\u00e0 de desenvolupament personal i col\u00b7lectiu. Si es duen a terme amb una ment oberta, s\u00f3n un factor insubstitu\u00efble d&#8217;autoeducaci\u00f3, toler\u00e0ncia m\u00fatua i aprenentatge de les leg\u00edtimes difer\u00e8ncies i cultures i de la seua diversitat. Tots tenim una [&hellip;]","og_url":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/","og_site_name":"Turismo Olocau","article_publisher":"https:\/\/www.facebook.com\/Turisme-Olocau-110345021644060","article_modified_time":"2026-04-22T08:26:25+00:00","og_image":[{"width":202,"height":253,"url":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@turismeolocau","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/","url":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/","name":"El Turista i Viatger Responsable - Turismo Olocau","isPartOf":{"@id":"https:\/\/turisme.olocau.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/#primaryimage"},"image":{"@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/#primaryimage"},"thumbnailUrl":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png","datePublished":"2022-09-12T15:06:03+00:00","dateModified":"2026-04-22T08:26:25+00:00","breadcrumb":{"@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/#breadcrumb"},"inLanguage":"val","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/"]}]},{"@type":"ImageObject","inLanguage":"val","@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/#primaryimage","url":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png","contentUrl":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/06\/muestras.png"},{"@type":"BreadcrumbList","@id":"https:\/\/turisme.olocau.es\/ca\/el-turista-i-viatger-responsable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/turisme.olocau.es\/ca\/"},{"@type":"ListItem","position":2,"name":"El Turista i Viatger Responsable"}]},{"@type":"WebSite","@id":"https:\/\/turisme.olocau.es\/ca\/#website","url":"https:\/\/turisme.olocau.es\/ca\/","name":"Turismo Olocau","description":"Visita Olocau","publisher":{"@id":"https:\/\/turisme.olocau.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turisme.olocau.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"val"},{"@type":"Organization","@id":"https:\/\/turisme.olocau.es\/ca\/#organization","name":"Turismo Olocau","url":"https:\/\/turisme.olocau.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"val","@id":"https:\/\/turisme.olocau.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/07\/Logo-Olocau-turismo_color.png","contentUrl":"https:\/\/turisme.olocau.es\/wp-content\/uploads\/2022\/07\/Logo-Olocau-turismo_color.png","width":300,"height":123,"caption":"Turismo Olocau"},"image":{"@id":"https:\/\/turisme.olocau.es\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Turisme-Olocau-110345021644060","https:\/\/x.com\/turismeolocau","https:\/\/www.instagram.com\/turismeolocau\/"]}]}},"_edit_lock":"1776846392:2","_wpml_word_count":"1653","_wp_page_template":"default","_edit_last":"","_elementor_edit_mode":"builder","_elementor_template_type":"wp-page","_elementor_version":"3.8.0","_elementor_pro_version":"3.26.3","_elementor_data":"[{\"id\":\"25edd5fd\",\"elType\":\"section\",\"settings\":{\"layout\":\"full_width\",\"margin\":{\"unit\":\"px\",\"top\":\"-100\",\"right\":0,\"bottom\":\"-100\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"_element_id\":\"arriba\"},\"elements\":[{\"id\":\"340ecdf7\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"33525be3\",\"elType\":\"widget\",\"settings\":{\"slides\":[{\"heading\":\"\",\"description\":\"\",\"button_text\":\"\",\"_id\":\"f782748\",\"background_image\":{\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/JLBI3467.jpg\",\"id\":2754,\"alt\":\"\",\"source\":\"library\"},\"background_ken_burns\":\"yes\",\"custom_style\":\"yes\",\"horizontal_position\":\"center\",\"vertical_position\":\"top\",\"__globals__\":{\"background_color\":\"globals\\\/colors?id=primary\"},\"index\":0}],\"slides_height\":{\"unit\":\"px\",\"size\":499,\"sizes\":[]},\"_margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"navigation\":\"none\",\"pause_on_hover\":\"\",\"pause_on_interaction\":\"\",\"content_animation\":\"fadeInLeft\",\"content_max_width\":{\"unit\":\"%\",\"size\":100,\"sizes\":[]},\"slides_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"heading_spacing\":{\"unit\":\"px\",\"size\":0,\"sizes\":[]},\"heading_color\":\"#FFFFFF\",\"heading_typography_typography\":\"custom\",\"heading_typography_font_family\":\"Montserrat\",\"heading_typography_font_size\":{\"unit\":\"px\",\"size\":44,\"sizes\":[]},\"heading_typography_font_weight\":\"300\",\"description_typography_typography\":\"custom\",\"description_typography_font_family\":\"Montserrat\",\"description_typography_font_size\":{\"unit\":\"px\",\"size\":44,\"sizes\":[]},\"description_typography_font_weight\":\"300\",\"button_size\":\"xs\",\"button_typography_typography\":\"custom\",\"button_typography_font_family\":\"Montserrat\",\"button_typography_font_size\":{\"unit\":\"px\",\"size\":44,\"sizes\":[]},\"button_typography_font_weight\":\"300\",\"button_text_color\":\"#FFFFFF\",\"custom_css\":\".elementor-slide-heading::first-line {\\n    background-color: #C42A1E;\\n    padding:3px 10px;\\n    max-width:100%;\\n    margin: 0 auto;\\n}\\n.elementor-slide-description::first-line {\\n    background-color: #D67D1F;\\n    padding:0px 10px;\\n    margin:10px auto;\\n    max-width:100%;\\n}\\n.elementor-slide-description {\\n    margin:10px auto;\\n}\",\"__globals__\":{\"button_background_color\":\"globals\\\/colors?id=136950b4\",\"button_border_color\":\"globals\\\/colors?id=136950b4\"},\"infinite\":\"\",\"transition\":\"fade\",\"slides_name\":\"Diapositivas\"},\"elements\":[],\"widgetType\":\"slides\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"2fa9385\",\"elType\":\"section\",\"settings\":{\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"z_index\":2},\"elements\":[{\"id\":\"71b407d0\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"2c3c4bae\",\"elType\":\"widget\",\"settings\":{\"image\":{\"url\":\"https:\\\/\\\/turisme.olocau.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/muestras.png\",\"id\":2634,\"alt\":\"\",\"source\":\"library\"},\"align\":\"left\",\"_margin\":{\"unit\":\"px\",\"top\":\"-1\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"_padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"align_mobile\":\"right\",\"caption\":\"\"},\"elements\":[],\"widgetType\":\"image\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"2c5b443d\",\"elType\":\"section\",\"settings\":{\"margin\":{\"unit\":\"px\",\"top\":\"-100\",\"right\":0,\"bottom\":\"50\",\"left\":0,\"isLinked\":false}},\"elements\":[{\"id\":\"61481f0e\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"padding_mobile\":{\"unit\":\"px\",\"top\":\"138\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"6363653e\",\"elType\":\"widget\",\"settings\":{\"title\":\"El Turista i Viatger Responsable\",\"align\":\"center\",\"__globals__\":{\"title_color\":\"globals\\\/colors?id=text\"}},\"elements\":[],\"widgetType\":\"heading\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"4de425e8\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"50\",\"right\":0,\"bottom\":\"0\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"81e33f0\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false}},\"elements\":[{\"id\":\"b5a8f9e\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Els viatges i el turisme haurien de concebre's i practicar-se com un mitj\\u00e0 de desenvolupament personal i col\\u00b7lectiu. Si es duen a terme amb una ment oberta, s\\u00f3n un factor insubstitu\\u00efble d'autoeducaci\\u00f3, toler\\u00e0ncia m\\u00fatua i aprenentatge de les leg\\u00edtimes difer\\u00e8ncies i cultures i de la seua diversitat. <\\\/p>\\n<p>Tots tenim una funci\\u00f3 que complir en la generaci\\u00f3 de viatges i turisme responsables. Els governs, les empreses i les comunitats han de procurar-ho sens dubte per tots els mitjans, per\\u00f2 vost\\u00e9 tamb\\u00e9, en la seua qualitat de visitant, pot secundar sensiblement aquest objectiu de moltes maneres: <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"410b5ec\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"85ead58\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"3388944\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-star-and-crescent\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"e1f0781\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"0db1b6d\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p><b>\\u00d2briga's a les cultures i tradicions diferents de les seues:<\\\/b> la seua experi\\u00e8ncia es veur\\u00e0 transformada, vost\\u00e9 es guanyar\\u00e0 el respecte de la poblaci\\u00f3 local, i aquesta l'acollir\\u00e0 m\\u00e9s f\\u00e0cilment. Siga tolerant i respecte la diversitat; observe les tradicions i les pr\\u00e0ctiques socials i culturals del lloc. <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"55d0173\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"9de6275\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"9822e9d\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-person-booth\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"64cc6b4\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"4e4ef8c\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p><b>Respecte els drets humans. <\\\/b>Qualsevol forma d'explotaci\\u00f3 vulnera els objectius fonamentals del turisme. L'explotaci\\u00f3 sexual infantil \\u00e9s un delicte punible, tant en el lloc on es duga a terme com al pa\\u00eds de resid\\u00e8ncia de qui el cometa. <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"f733736\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"17e3d65\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"0e804f7\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-tree\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"6ec828b\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"3e0a52f\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p><b>Ajude a conservar l'entorn natural. <\\\/b>Protegisca la flora i fauna silvestre i el seu h\\u00e0bitat, i no compre productes elaborats a partir de plantes o animals en perill d'extinci\\u00f3.<\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"5312e57\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"dedff60\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"760f9bf\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-boxes\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"064b2b4\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"e15aae9\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p><b>Respecte els recursos culturals. <\\\/b>Les activitats tur\\u00edstiques han de practicar-se amb respecte pel patrimoni art\\u00edstic, arqueol\\u00f2gic i cultural.<\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"ab4432a\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"0842528\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"bbdedd4\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-ticket-alt\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"8f7ac34\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"18ac758\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p data-pm-slice=\\\"1 1 []\\\"><strong>Contribueixi al desenvolupament econ\\u00f2mic i social<\\\/strong>. Compri artesania i productes locals per a donar suport a l'economia del lloc, i atingui's als principis del comer\\u00e7 just. Quan regategi, tingui present el concepte de salari just.<\\\/p>\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"fb59e5e\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"010852b\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.997,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"7abd70c\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-ambulance\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"ad4ee80\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.003,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"063ec70\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Abans d'eixir de viatge, i<b>nforme's sobre la situaci\\u00f3 sanit\\u00e0ria actual del seu dest\\u00ed<\\\/b> i sobre l'acc\\u00e9s en ell a serveis consulars i d'emerg\\u00e8ncia, i assegure's que la seua salut i la seua seguretat personal no correran perill. Cerciore's de tindre cobertes all\\u00ed les seues necessitats espec\\u00edfiques (alimentaci\\u00f3, accessibilitat o atenci\\u00f3 m\\u00e8dica) abans de decidir-se a viatjar a un dest\\u00ed determinat. <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"59e6878\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"b8aaf91\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"5a64b01\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-torah\",\"library\":\"fa-solid\"}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"91b860a\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"bc7639d\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Reunisca tota la informaci\\u00f3 possible sobre el seu dest\\u00ed, i <b>dedique temps a entendre els seus costums, normes i tradicions.<\\\/b> Evite els comportaments que puguen ofendre a la poblaci\\u00f3 local. <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"348f010\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"10\",\"right\":0,\"bottom\":\"10\",\"left\":0,\"isLinked\":true},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true},\"structure\":\"20\"},\"elements\":[{\"id\":\"2f80cd3\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":12.998,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"b843d4a\",\"elType\":\"widget\",\"settings\":{\"selected_icon\":{\"value\":\"fas fa-capsules\",\"library\":\"fa-solid\"},\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"icon\"}],\"isInner\":false},{\"id\":\"4a495af\",\"elType\":\"column\",\"settings\":{\"_column_size\":50,\"_inline_size\":87.002,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"2969d13\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p><b>Informe's de la legislaci\\u00f3 vigent<\\\/b> per a no cometre cap acte que es considere delictiu al pa\\u00eds visitat. No trafique amb drogues, armes, antiguitats, esp\\u00e8cies protegides, productes o subst\\u00e0ncies perilloses o prohibides pels reglaments nacionals. <\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"5bc6084\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"100\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"b0547de\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"2b02988\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<p>Aquests consells es basen en el <i>Codi \\u00c8tic Mundial per al Turisme<\\\/i> de l'Organitzaci\\u00f3 Mundial del Turisme.<\\\/p>\\n\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false},{\"id\":\"0fc9b38\",\"elType\":\"section\",\"settings\":{\"content_width\":{\"unit\":\"px\",\"size\":900,\"sizes\":[]},\"gap\":\"extended\",\"custom_height\":{\"unit\":\"px\",\"size\":267,\"sizes\":[]},\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":0,\"bottom\":\"100\",\"left\":0,\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"65d71bc\",\"elType\":\"column\",\"settings\":{\"_column_size\":100,\"_inline_size\":null,\"margin\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"10\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":false},\"padding\":{\"unit\":\"px\",\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\",\"isLinked\":true}},\"elements\":[{\"id\":\"14d6450\",\"elType\":\"widget\",\"settings\":{\"editor\":\"<div class=\\\"blog-post \\\"><div class=\\\"container\\\" role=\\\"main\\\" aria-label=\\\"Contenido principal\\\"><article id=\\\"post-3810\\\" class=\\\"section section-text\\\"><div class=\\\"row\\\"><div class=\\\"col-md-8 page-content-wrap col-md-offset-2\\\"><div class=\\\"blog-post \\\"><div class=\\\"container\\\" role=\\\"main\\\" aria-label=\\\"Contenido principal\\\"><article id=\\\"post-3810\\\" class=\\\"section section-text\\\"><div class=\\\"row\\\"><h1>Drets i obligacions del turista<\\\/h1><h4>La Comunitat Valenciana compta amb la Llei de Turisme, que estableix els drets de les persones usu\\u00e0ries de serveis i productes tur\\u00edstics.<\\\/h4><p>La LLEI 15\\\/2018, 7 de juny, de turisme, oci i hospitalitat de la Comunitat Valenciana contempla l'impuls de l'hospitalitat com a element b\\u00e0sic en la relaci\\u00f3 entre residents i turistes.<\\\/p><p>Aquesta Llei defineix l'Hospitalitat com la \\u201catenci\\u00f3 i tracte proporcionat a les persones usu\\u00e0ries de serveis tur\\u00edstics des del respecte al seu idioma, h\\u00e0bits, tradicions, creences i llibertat de consci\\u00e8ncia, amb la finalitat de proporcionar la major satisfacci\\u00f3 possible de les seues expectatives d'acord amb els valors que ens identifiquen com a societat oberta, tolerant i mediterr\\u00e0nia.\\u201d<\\\/p><p>Els Articles 16 i 17 de la citada Llei desenvolupen els drets i deures dels usuaris dels serveis tur\\u00edstics per a preservar aquest pilar central de la relaci\\u00f3 entre els turistes que ens visiten i el nostre dest\\u00ed:<\\\/p><p>\\u00a0<\\\/p><p><br \\\/><strong>Article 16. Drets<\\\/strong><\\\/p><p>Les persones usu\\u00e0ries de serveis tur\\u00edstics, sense perjudici del que es disposa en la legislaci\\u00f3 general de defensa i protecci\\u00f3 dels consumidors, tindran dret a:<\\\/p><p>Rebre de les empreses tur\\u00edstiques informaci\\u00f3 objectiva, vera\\u00e7 i comprensible, completa i pr\\u00e8via a la seua contractaci\\u00f3 sobre els serveis que se'ls oferisquen, aix\\u00ed com sobre el preu final, inclosos els impostos. I a ser protegit enfront de la informaci\\u00f3 o publicitat enganyosa conformement a la normativa vigent.<br \\\/>Obtindre els documents que acrediten els termes de la seua contractaci\\u00f3.<br \\\/>Rebre els serveis tur\\u00edstics en les condicions oferides o pactades i, en tot cas, que la naturalesa i qualitat de la seua prestaci\\u00f3 guarde proporci\\u00f3 directa amb la categoria de l'empresa o establiment tur\\u00edstic.<br \\\/>Gaudir d'uns espais, infraestructures i serveis tur\\u00edstics accessibles.<br \\\/>Accedir lliurement als establiments i serveis tur\\u00edstics en els termes establits en les lleis.<br \\\/>Que els establiments tur\\u00edstics complisquen la normativa sobre seguretat de les seues instal\\u00b7lacions i protecci\\u00f3 contra incendis aix\\u00ed com l'espec\\u00edfica en mat\\u00e8ria tur\\u00edstica.<br \\\/>Ser informats, de manera clara, sobre les instal\\u00b7lacions o serveis que puguen suposar algun risc i de les mesures de seguretat adoptades sobre aquest tema.<br \\\/>Rebre una factura o justificant de pagament del servei tur\\u00edstic prestat amb les dades que la legislaci\\u00f3 vigent exigisca.<br \\\/>Formular queixes i reclamacions i obtindre informaci\\u00f3 accessible i vera\\u00e7 sobre el procediment de presentaci\\u00f3 de les mateixes i el seu tractament, podent acudir a un sistema de soluci\\u00f3 extrajudicial de conflictes a trav\\u00e9s de la mediaci\\u00f3 i l'arbitratge. Aix\\u00ed mateix, tenen dret al fet que l'administraci\\u00f3 p\\u00fablica competent procure la m\\u00e0xima efic\\u00e0cia en l'atenci\\u00f3 i tramitaci\\u00f3 de les seues queixes o reclamacions formulades.<br \\\/>Acudir a f\\u00f3rmules d'arbitratge per a la resoluci\\u00f3 extrajudicial dels seus conflictes amb conseq\\u00fc\\u00e8ncies econ\\u00f2miques.<br \\\/>Exigir que, en un lloc de f\\u00e0cil visibilitat, s'exhibisquen p\\u00fablicament els distintius acreditatius de la classificaci\\u00f3 de l'establiment, l'aforament, els preus dels serveis oferits i qualsevol altra variable d'activitat, aix\\u00ed com els s\\u00edmbols de qualitat corresponents.<\\\/p><p>\\u00a0<\\\/p><p><br \\\/><strong>Article 17. Obligacions<\\\/strong><\\\/p><p>Les persones usu\\u00e0ries de serveis tur\\u00edstics, sense perjudici del que disposen les normatives sectorials que siguen aplicable, tindran les seg\\u00fcents obligacions:<\\\/p><p>Respectar les tradicions i pr\\u00e0ctiques socials i culturals de les destinacions tur\\u00edstiques, aix\\u00ed com la seua riquesa i valor.<br \\\/>Respectar l'entorn mediambiental, el patrimoni hist\\u00f2ric i cultural i els recursos tur\\u00edstics.<br \\\/>Abonar els serveis contractats, ja siga en el moment de la presentaci\\u00f3 de la factura o en el temps, lloc i forma convinguts, sense que el fet de presentar una reclamaci\\u00f3 o queixa implique, en cap cas, l'exempci\\u00f3 de pagament.<br \\\/>En el cas del servei tur\\u00edstic d'allotjament, respectar la data i hora pactades d'eixida de l'establiment, deixant lliure la unitat d'allotjament ocupada.<br \\\/>Observar les regles de respecte, educaci\\u00f3, conviv\\u00e8ncia social, indument\\u00e0ria i higiene per a l'adequada utilitzaci\\u00f3 dels establiments i serveis tur\\u00edstics.<br \\\/>Respectar les instal\\u00b7lacions i equipaments dels establiments i empreses tur\\u00edstiques.<br \\\/>Respectar les normes de r\\u00e8gim interior dels establiments tur\\u00edstics, els horaris i les regles de conducta dels llocs de visita i de realitzaci\\u00f3 d'activitats tur\\u00edstiques.<\\\/p><p><strong>M\\u00e9s\\u2026<\\\/strong><\\\/p><p>Els viatgers i el turista haurien de concebre's com un mitj\\u00e0 de desenvolupament personal i col\\u00b7lectiu. Si es duen a terme amb una ment oberta, s\\u00f3n un factor insubstitu\\u00efble d'acte educaci\\u00f3, toler\\u00e0ncia m\\u00fatua i aprenentatge de les leg\\u00edtimes diferencies ens pobles i cultures i de la seua diversitat.<\\\/p><p>Tots tenim una funci\\u00f3 que complir en la generaci\\u00f3 de viatges i turisme responsables. Els governs, les empreses i les comunitats han de procurar el sens dubte per tots els mitjans, per\\u00f2 vost\\u00e9 tamb\\u00e9, en la seua qualitat de visitant, pot secundar sensiblement aquest objectiu de moltes maneres:<\\\/p><ul><li>\\u00d2briga's a les cultures i tradicions diferents de les seues: la seua experi\\u00e8ncia es veur\\u00e0 transformada, vost\\u00e9 es guanyar\\u00e0 el respecte de les poblaci\\u00f3 local, i aquesta l'acollir\\u00e0 m\\u00e9s f\\u00e0cilment. Siga tolerant i respecte la diversitat; observe les tradicions i les pr\\u00e0ctiques socials i culturals del lloc.<\\\/li><li>Respecte els drets humans. Qualsevol forma d'explotaci\\u00f3 vulnera els objectius fonamentals del turisme. L'explotaci\\u00f3 sexual infantil \\u00e9s un delicte punible, tant en el lloc on \\u00e9s duga a terme com al pa\\u00eds de resid\\u00e8ncia de qui el cometa.<\\\/li><li>Ajude a conservar l'entorn natural. Protegisca la flora i la fauna silvestre i el seu h\\u00e0bitat, i no compre productes elaborats a partir de plantes o animals en perill d'extinci\\u00f3.<\\\/li><li>Respecte els recursos culturals. Les activitats tur\\u00edstiques han de practicar-se amb respecte pel patrimoni art\\u00edstics, arqueol\\u00f2gic i cultural.<\\\/li><li>El seu viatge pot contribuir al desenvolupament econ\\u00f2mic i social. Compre artesania i productes locals per a donar suport a l'economia del lloc, i atinga's als principis del comer\\u00e7 just. Quan regatege, tinga premse el concepte del salari just.<\\\/li><li>Abans d'eixir de viatge, informe's sobre la situaci\\u00f3 sanit\\u00e0ria actual del seu dest\\u00ed i sobre l'acc\\u00e9s en ell a serveis consulars i d'emerg\\u00e8ncia, i assegure's que la seua salut i la seua seguretat personal no correran perill. Cerciore's de tindre cobertes all\\u00ed les seues necessitats espec\\u00edfiques (alimentaci\\u00f3, accessibilitat o atenci\\u00f3 m\\u00e8dica) abans de decidir-se a viatjar a un dest\\u00ed determinat.<\\\/li><li>Reunisca tota la informaci\\u00f3 possible sobre el seu dest\\u00ed, i dedique temps a entendre els seus costums, normes i tradicions. Evite els comportaments que puguen ofendre a la poblaci\\u00f3 local.<br \\\/>Informe's de la legislaci\\u00f3 vigent per a no cometre cap acte que es considere delictiu al pa\\u00eds visitat. No trafique amb drogues, armes, antiguitats, espeies protegides, ni productes o subst\\u00e0ncies perillosos o prohibits pels reglaments nacionals.<\\\/li><\\\/ul><\\\/div><\\\/article><\\\/div><\\\/div><\\\/div><\\\/div><\\\/article><\\\/div><\\\/div>\",\"_padding_mobile\":{\"unit\":\"px\",\"top\":\"9\",\"right\":\"6\",\"bottom\":\"0\",\"left\":\"19\",\"isLinked\":false}},\"elements\":[],\"widgetType\":\"text-editor\"}],\"isInner\":false}],\"isInner\":false}]","_elementor_page_assets":{"styles":["e-animation-fadeInLeft","e-swiper","widget-slides","widget-image","widget-heading"],"scripts":["imagesloaded","elementor-frontend"]},"_yoast_wpseo_content_score":"30","_yoast_wpseo_estimated-reading-time-minutes":"9","_elementor_page_settings":{"hide_title":"yes"},"_elementor_controls_usage":{"slides":{"count":1,"control_percent":5,"controls":{"content":{"section_slides":{"slides":1,"slides_height":1},"section_slider_options":{"navigation":1,"pause_on_hover":1,"pause_on_interaction":1,"content_animation":1,"infinite":1,"transition":1}},"advanced":{"_section_style":{"_margin":1,"_padding":1},"section_custom_css":{"custom_css":1}},"style":{"section_style_slides":{"content_max_width":1,"slides_padding":1},"section_style_title":{"heading_spacing":1,"heading_color":1,"heading_typography_typography":1,"heading_typography_font_family":1,"heading_typography_font_size":1,"heading_typography_font_weight":1},"section_style_description":{"description_typography_typography":1,"description_typography_font_family":1,"description_typography_font_size":1,"description_typography_font_weight":1},"section_style_button":{"button_size":1,"button_typography_typography":1,"button_typography_font_family":1,"button_typography_font_size":1,"button_typography_font_weight":1,"button_text_color":1}}}},"column":{"count":22,"control_percent":1,"controls":{"layout":{"layout":{"_inline_size":22}},"advanced":{"section_advanced":{"margin":21,"padding":21,"padding_mobile":1}}}},"section":{"count":14,"control_percent":1,"controls":{"layout":{"section_layout":{"layout":1,"content_width":11,"gap":11,"custom_height":11},"section_structure":{"structure":8}},"advanced":{"section_advanced":{"margin":14,"padding":13,"_element_id":1,"z_index":1}}}},"image":{"count":1,"control_percent":1,"controls":{"content":{"section_image":{"image":1}},"style":{"section_style_image":{"align":1,"align_mobile":1}},"advanced":{"_section_style":{"_margin":1,"_padding":1}}}},"heading":{"count":1,"control_percent":0,"controls":{"content":{"section_title":{"title":1}},"style":{"section_title_style":{"align":1}}}},"text-editor":{"count":11,"control_percent":0,"controls":{"content":{"section_editor":{"editor":11}},"advanced":{"_section_style":{"_padding_mobile":11}}}},"icon":{"count":8,"control_percent":0,"controls":{"content":{"section_icon":{"selected_icon":8}},"advanced":{"_section_style":{"_padding_mobile":1}}}}},"_wpml_media_featured":"1","_wpml_media_duplicate":"0","_top_nav_excluded":"","_cms_nav_minihome":"","_elementor_template_widget_type":"","_last_translation_edit_mode":"native-editor","_yoast_wpseo_focuskw":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_linkdex":"","_yoast_wpseo_wordproof_timestamp":"","_thumbnail_id":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_opengraph-image":"","_yoast_wpseo_opengraph-image-id":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_twitter-image":"","_yoast_wpseo_twitter-image-id":"","_elementor_css":{"time":1788335687,"fonts":["Montserrat"],"icons":["fa-solid"],"dynamic_elements_ids":[],"status":"file","0":""},"_cdp_origin":"","_cdp_origin_site":"","_cdp_origin_title":"","_cdp_counter":"","_oembed_1715d3fe5f1b4894d69c403ed95c6d1f":"","_oembed_7b3a3160db89c87d5fa3541f189de6fa":"","_wpml_post_translation_editor_native":"","_wp_trash_meta_status":"","_wp_trash_meta_time":"","_wp_desired_post_slug":"","_links":{"self":[{"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/pages\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":8,"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/pages\/3434\/revisions"}],"predecessor-version":[{"id":13368,"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/pages\/3434\/revisions\/13368"}],"wp:attachment":[{"href":"https:\/\/turisme.olocau.es\/ca\/wp-json\/wp\/v2\/media?parent=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}